{"id":4545,"date":"2025-12-05T08:56:08","date_gmt":"2025-12-05T07:56:08","guid":{"rendered":"https:\/\/act-greensefa.admk-dev.de\/make-them-pay\/"},"modified":"2026-02-28T22:18:52","modified_gmt":"2026-02-28T21:18:52","slug":"make-them-pay","status":"publish","type":"page","link":"https:\/\/act.greens-efa.eu\/fr\/make-them-pay\/","title":{"rendered":"Taxer les tech bros : make them pay"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4545\" class=\"elementor elementor-4545 elementor-3596\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-444c612d e-con-full e-flex e-con e-parent\" data-id=\"444c612d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet_extra&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t<div class=\"elementor-element elementor-element-7e7f42e8 e-con-full e-flex e-con e-child\" data-id=\"7e7f42e8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2f06e562 colored-headline-bg-yes elementor-widget elementor-widget-heading\" data-id=\"2f06e562\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Taxer les tech bros : make them pay\n<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1dbaceb9 e-con-full e-flex e-con e-parent\" data-id=\"1dbaceb9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-238056a9 e-con-full hideElement e-flex elementor-invisible e-con e-child\" data-id=\"238056a9\" data-element_type=\"container\" data-e-type=\"container\" id=\"goToAction\" data-settings=\"{&quot;position&quot;:&quot;fixed&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7c6229c7 elementor-widget__width-auto elementor-invisible elementor-widget elementor-widget-button\" data-id=\"7c6229c7\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"GoToActionBtn\" data-settings=\"{&quot;_animation&quot;:&quot;rubberBand&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#take-action\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M413.1 222.5l22.2 22.2c9.4 9.4 9.4 24.6 0 33.9L241 473c-9.4 9.4-24.6 9.4-33.9 0L12.7 278.6c-9.4-9.4-9.4-24.6 0-33.9l22.2-22.2c9.5-9.5 25-9.3 34.3.4L184 343.4V56c0-13.3 10.7-24 24-24h32c13.3 0 24 10.7 24 24v287.4l114.8-120.5c9.3-9.8 24.8-10 34.3-.4z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Take action<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-113d1e82 e-con-full elementor-hidden-mobile e-flex e-con e-child\" data-id=\"113d1e82\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5d9bd0e6 e-con-full e-flex e-con e-child\" data-id=\"5d9bd0e6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-676d05fa e-con-full e-flex e-con e-child\" data-id=\"676d05fa\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a71dc11 elementor-widget elementor-widget-text-editor\" data-id=\"a71dc11\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"preamble\" dir=\"ltr\">Les citoyen\u00b7nes europ\u00e9en\u00b7nes travaillent dur pour gagner leur vie et subvenir aux besoins de leur famille. Pendant ce temps, les dirigeants ultra-riches des g\u00e9ants de la tech engrangent des b\u00e9n\u00e9fices records sans contribuer \u00e0 la soci\u00e9t\u00e9. Et tout cela avec le soutien du pr\u00e9sident am\u00e9ricain Donald Trump.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-106e219c elementor-widget elementor-widget-heading\" data-id=\"106e219c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Il est temps de leur tenir t\u00eate et de les faire contribuer (\u00e0 travers une taxe sur les services num\u00e9riques).\n<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-faabeb5 elementor-widget elementor-widget-text-editor\" data-id=\"faabeb5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p dir=\"ltr\">Les travailleuses et les travailleurs et les petites entreprises sont le pilier de l&rsquo;\u00e9conomie europ\u00e9enne. En payant des imp\u00f4ts sur leurs salaires ou sur leurs b\u00e9n\u00e9fices, ils financent les services publics essentiels dont nous b\u00e9n\u00e9ficions toutes et tous. Gr\u00e2ce \u00e0 ces contributions, nous finan\u00e7ons nos \u00e9coles, nos h\u00f4pitaux, nos routes et nos transports publics. Les travailleuses et les travailleurs sont les v\u00e9ritables moteurs de notre soci\u00e9t\u00e9.<\/p><p dir=\"ltr\">Or, \u00e0 l&rsquo;heure actuelle, une poign\u00e9e de g\u00e9ants du num\u00e9rique et leurs propri\u00e9taires, des \u00ab tech bros \u00bb, engrangent des milliards d&rsquo;euros sans contribuer un centime \u00e0 nos soci\u00e9t\u00e9s. C&rsquo;est inacceptable. Nous devons emp\u00eacher Elon Musk, Jeff Bezos et Mark Zuckerberg de s&rsquo;enrichir \u00e0 nos d\u00e9pens.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf9a803 elementor-widget elementor-widget-image\" data-id=\"cf9a803\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"\" fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/act.greens-efa.eu\/wp-content\/uploads\/2026\/01\/bakery2-e1769530702240.jpg\" class=\"attachment-large size-large wp-image-4560\" alt=\"\" srcset=\"https:\/\/act.greens-efa.eu\/wp-content\/uploads\/2026\/01\/bakery2-e1769530702240.jpg 1000w, https:\/\/act.greens-efa.eu\/wp-content\/uploads\/2026\/01\/bakery2-e1769530702240-300x169.jpg 300w, https:\/\/act.greens-efa.eu\/wp-content\/uploads\/2026\/01\/bakery2-e1769530702240-768x432.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-06d79cc elementor-widget elementor-widget-heading\" data-id=\"06d79cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Ils doivent payer leur juste part d'imp\u00f4ts en Europe. Et nous pouvons les y contraindre.\n<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47e0d30 elementor-widget elementor-widget-text-editor\" data-id=\"47e0d30\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<section class=\"rich-text-media\"><div class=\"rich-text-media-inner  \"><div class=\"rich-text-column\"><p dir=\"ltr\">\u00c0 l&rsquo;heure actuelle, les grandes entreprises du num\u00e9rique font des milliards de b\u00e9n\u00e9fices en Europe gr\u00e2ce aux achats en ligne, \u00e0 la publicit\u00e9 num\u00e9rique, au streaming et aux services de \u00ab cloud \u00bb. Pourtant, elles ne paient des imp\u00f4ts que l\u00e0 o\u00f9 se trouve leur si\u00e8ge social, souvent dans des pays \u00e0 faible fiscalit\u00e9. Cela signifie qu&rsquo;elles profitent des consommatrices et des consommateurs et des march\u00e9s europ\u00e9ens sans contribuer \u00e9quitablement \u00e0 nos soci\u00e9t\u00e9s. Gr\u00e2ce \u00e0 une taxe sur les services num\u00e9riques, l&rsquo;Union europ\u00e9enne pourrait collecter plus de 37,5 milliards d&rsquo;euros par an, soit environ un cinqui\u00e8me de son budget annuel.<\/p><\/div><\/div><\/section><dl class=\"expandable expandableRichtext\"><\/dl>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-193f58b elementor-widget elementor-widget-image\" data-id=\"193f58b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/act.greens-efa.eu\/wp-content\/uploads\/2026\/01\/amazon-e1769530842464.jpg\" class=\"attachment-large size-large wp-image-4562\" alt=\"\" srcset=\"https:\/\/act.greens-efa.eu\/wp-content\/uploads\/2026\/01\/amazon-e1769530842464.jpg 1000w, https:\/\/act.greens-efa.eu\/wp-content\/uploads\/2026\/01\/amazon-e1769530842464-300x169.jpg 300w, https:\/\/act.greens-efa.eu\/wp-content\/uploads\/2026\/01\/amazon-e1769530842464-768x432.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c0fc60d e-con-full e-flex e-con e-child\" data-id=\"c0fc60d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-1b65fe1 e-flex e-con-boxed e-con e-child\" data-id=\"1b65fe1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-321d2fd elementor-absolute elementor-widget elementor-widget-image\" data-id=\"321d2fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"\" decoding=\"async\" width=\"309\" height=\"265\" src=\"https:\/\/act.greens-efa.eu\/wp-content\/uploads\/2025\/11\/faq_flag-2.svg\" class=\"attachment-full size-full wp-image-4561\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32e42dd elementor-widget elementor-widget-n-accordion\" data-id=\"32e42dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;multiple&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-5330\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-5330\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h3 class=\"e-n-accordion-item-title-text\"> Comment fonctionnerait la taxe sur les services num\u00e9riques ? <\/h3><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_1\" viewBox=\"0 0 32 32\"><polygon points=\"8.9 14.6 0 14.6 0 17.4 32 17.4 32 14.6 8.9 14.6\"><\/polygon><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_1\" viewBox=\"0 0 32 32\"><polygon points=\"32 14.6 17.4 14.6 17.4 8.9 17.4 0 14.6 0 14.6 14.6 8.9 14.6 0 14.6 0 17.4 14.6 17.4 14.6 32 17.4 32 17.4 17.4 32 17.4 32 14.6\"><\/polygon><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-5330\" class=\"elementor-element elementor-element-056333b e-con-full e-flex e-con e-child\" data-id=\"056333b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4eff14f elementor-widget elementor-widget-text-editor\" data-id=\"4eff14f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p dir=\"ltr\">Le projet est simple :<\/p><ul><li dir=\"ltr\"><p dir=\"ltr\">Une petite taxe de 5 %, \u00e0 l&rsquo;\u00e9chelle de l&rsquo;Union europ\u00e9enne, sur les revenus que ces entreprises tirent des services num\u00e9riques au sein de l&rsquo;Union, quel que soit leur lieu d&rsquo;implantation.<\/p><\/li><li dir=\"ltr\"><p dir=\"ltr\">Cette taxe ne s&rsquo;appliquerait qu&rsquo;aux plus grands acteurs, c&rsquo;est-\u00e0-dire aux entreprises dont le chiffre d&rsquo;affaires annuel s&rsquo;\u00e9l\u00e8ve \u00e0 plusieurs centaines de millions d&rsquo;euros. Les petites start-ups et entreprises europ\u00e9ennes ne seraient pas concern\u00e9es.<\/p><\/li><li dir=\"ltr\"><p dir=\"ltr\">Les recettes de cette taxe viendraient abonder le budget de l&rsquo;Union europ\u00e9enne en tant que \u00ab ressource propre \u00bb, ce qui permettrait \u00e0 l&rsquo;Union de les investir dans ses priorit\u00e9s.<\/p><\/li><\/ul><p>Selon <a href=\"https:\/\/api.rasmus-andresen.eu\/wp-content\/uploads\/2025\/04\/Study_Toward-a-European-digital-tax_01042025_RasmusANDRESEN_final.pdf\">notre nouvelle \u00e9tude<\/a>, une telle taxe pourrait rapporter plus de 37,5 milliards d&rsquo;euros par an d&rsquo;ici 2026. Et ce montant continuerait d&rsquo;augmenter \u00e0 mesure que l&rsquo;\u00e9conomie num\u00e9rique se d\u00e9veloppe.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-5331\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-5331\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h3 class=\"e-n-accordion-item-title-text\"> Si nous payons des imp\u00f4ts, pourquoi pas eux ? <\/h3><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_1\" viewBox=\"0 0 32 32\"><polygon points=\"8.9 14.6 0 14.6 0 17.4 32 17.4 32 14.6 8.9 14.6\"><\/polygon><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_1\" viewBox=\"0 0 32 32\"><polygon points=\"32 14.6 17.4 14.6 17.4 8.9 17.4 0 14.6 0 14.6 14.6 8.9 14.6 0 14.6 0 17.4 14.6 17.4 14.6 32 17.4 32 17.4 17.4 32 17.4 32 14.6\"><\/polygon><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-5331\" class=\"elementor-element elementor-element-88d9176 e-flex e-con-boxed e-con e-child\" data-id=\"88d9176\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b42f37b elementor-widget elementor-widget-text-editor\" data-id=\"b42f37b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<dl class=\"expandable expandableRichtext\"><dt class=\"expandable_title\" data-expanded=\"false\"><p dir=\"ltr\">Les g\u00e9ants du num\u00e9rique paient en moyenne seulement 9,5 % d&rsquo;imp\u00f4ts, tandis que les entreprises traditionnelles en paient plus de 23 %. Ce n&rsquo;est pas seulement injuste. C&rsquo;est une menace pour la d\u00e9mocratie.<\/p><p dir=\"ltr\">Ces grandes entreprises exploitent les failles fiscales pour \u00e9viter de contribuer \u00e0 la soci\u00e9t\u00e9. Les g\u00e9ants du num\u00e9rique engrangent des profits sur le dos des Europ\u00e9en\u00b7nes qui travaillent dur. Et il ne s&rsquo;agit pas seulement d&rsquo;argent.<\/p><p dir=\"ltr\">\u00c0 mesure que ces entreprises s&rsquo;enrichissent et deviennent plus puissantes, nos institutions d\u00e9mocratiques s&rsquo;affaiblissent. En effet, ces entreprises sapent la concurrence, \u00e9rodent la confiance dans les services publics et concentrent la richesse entre les mains de quelques-uns. Dans le m\u00eame temps, la majorit\u00e9 de la population est confront\u00e9e \u00e0 des in\u00e9galit\u00e9s croissantes, \u00e0 l&rsquo;ins\u00e9curit\u00e9 sociale et \u00e0 la r\u00e9duction des investissements publics.<\/p><\/dt><dd class=\"expandable_content\"><\/dd><\/dl>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"FAQPage\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"Comment fonctionnerait la taxe sur les services num\\u00e9riques ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Le projet est simple :Une petite taxe de 5 %, \\u00e0 l&rsquo;\\u00e9chelle de l&rsquo;Union europ\\u00e9enne, sur les revenus que ces entreprises tirent des services num\\u00e9riques au sein de l&rsquo;Union, quel que soit leur lieu d&rsquo;implantation.Cette taxe ne s&rsquo;appliquerait qu&rsquo;aux plus grands acteurs, c&rsquo;est-\\u00e0-dire aux entreprises dont le chiffre d&rsquo;affaires annuel s&rsquo;\\u00e9l\\u00e8ve \\u00e0 plusieurs centaines de millions d&rsquo;euros. Les petites start-ups et entreprises europ\\u00e9ennes ne seraient pas concern\\u00e9es.Les recettes de cette taxe viendraient abonder le budget de l&rsquo;Union europ\\u00e9enne en tant que \\u00ab ressource propre \\u00bb, ce qui permettrait \\u00e0 l&rsquo;Union de les investir dans ses priorit\\u00e9s.Selon notre nouvelle \\u00e9tude, une telle taxe pourrait rapporter plus de 37,5 milliards d&rsquo;euros par an d&rsquo;ici 2026. Et ce montant continuerait d&rsquo;augmenter \\u00e0 mesure que l&rsquo;\\u00e9conomie num\\u00e9rique se d\\u00e9veloppe.\"}},{\"@type\":\"Question\",\"name\":\"Si nous payons des imp\\u00f4ts, pourquoi pas eux ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Les g\\u00e9ants du num\\u00e9rique paient en moyenne seulement 9,5 % d&rsquo;imp\\u00f4ts, tandis que les entreprises traditionnelles en paient plus de 23 %. Ce n&rsquo;est pas seulement injuste. C&rsquo;est une menace pour la d\\u00e9mocratie.Ces grandes entreprises exploitent les failles fiscales pour \\u00e9viter de contribuer \\u00e0 la soci\\u00e9t\\u00e9. Les g\\u00e9ants du num\\u00e9rique engrangent des profits sur le dos des Europ\\u00e9en\\u00b7nes qui travaillent dur. Et il ne s&rsquo;agit pas seulement d&rsquo;argent.\\u00c0 mesure que ces entreprises s&rsquo;enrichissent et deviennent plus puissantes, nos institutions d\\u00e9mocratiques s&rsquo;affaiblissent. En effet, ces entreprises sapent la concurrence, \\u00e9rodent la confiance dans les services publics et concentrent la richesse entre les mains de quelques-uns. Dans le m\\u00eame temps, la majorit\\u00e9 de la population est confront\\u00e9e \\u00e0 des in\\u00e9galit\\u00e9s croissantes, \\u00e0 l&rsquo;ins\\u00e9curit\\u00e9 sociale et \\u00e0 la r\\u00e9duction des investissements publics.\"}}]}<\/script>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-38f1fbc elementor-widget elementor-widget-text-editor\" data-id=\"38f1fbc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p dir=\"ltr\">Faire payer aux milliardaires du secteur du num\u00e9rique leur juste part d&rsquo;imp\u00f4ts, permettra \u00e0 l\u2019Union europ\u00e9enne d\u2019avoir de nouvelles recettes \u00e0 investir dans ce dont les citoyen\u00b7nes europ\u00e9en\u00b7nes ont le plus besoin pour mener une vie agr\u00e9able : des services de garde d&rsquo;enfants abordables, des logements et la lutte contre le d\u00e9r\u00e8glement climatique. Ainsi nous aurions davantage de ressources propres pour le budget de l&rsquo;UE et pour nos citoyennes et nos citoyens.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ace6f2 elementor-widget elementor-widget-heading\" data-id=\"7ace6f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Si nous nous portons toutes et tous mieux, alors notre \u00e9conomie se portera \u00e9galement mieux.\n<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-efa05bf elementor-widget elementor-widget-text-editor\" data-id=\"efa05bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"cell petition-cell gl-content\"><div class=\"gl-content-wrapper\"><section class=\"rich-text gutter\"><div class=\"rich-text-inner\"><section class=\"rich-text gutter\"><div class=\"rich-text-inner\"><p dir=\"ltr\">N\u2019\u00eates-vous pas d\u2019accord ? Signez notre p\u00e9tition d\u00e8s maintenant.<\/p><\/div><\/section><\/div><\/section><section class=\"rich-text gutter\"><div class=\"rich-text-inner\"><p><strong>Rasmus Andresen \ud83c\udde9\ud83c\uddea &#8211; Jaume Asens \ud83c\udff4\udb40\udc65\udb40\udc73\udb40\udc63\udb40\udc74\udb40\udc7f &#8211; Saskia Bricmont\u00a0\ud83c\udde7\ud83c\uddea\u00a0&#8211; Anna Cavazzini\u00a0\ud83c\udde9\ud83c\uddea\u00a0&#8211; David Cormand\u00a0\ud83c\uddeb\ud83c\uddf7\u00a0&#8211; Alexandra Geese \ud83c\udde9\ud83c\uddea &#8211; Sara Matthieu\u00a0\ud83c\udde7\ud83c\uddea\u00a0&#8211; Maria Ohisalo \ud83c\uddeb\ud83c\uddee &#8211; Kira Peter-Hansen \ud83c\udde9\ud83c\uddf0 &#8211; Marie Toussaint \ud83c\uddeb\ud83c\uddf7<\/strong><\/p><div class=\"cell petition-cell gl-content\"><div class=\"gl-content-wrapper\"><section class=\"rich-text gutter\"><div class=\"rich-text-inner\"><p>Membres des Verts\/ALE au Parlement europ\u00e9en<\/p><\/div><\/section><\/div><\/div><\/div><\/section><\/div><\/div><div class=\"grid-container footer\"><div class=\"grid-x\"><div class=\"cell\">\u00a0<\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7acfd861 e-con-full e-flex e-con e-child\" data-id=\"7acfd861\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-40159a00 e-con-full e-transform e-flex e-con e-child\" data-id=\"40159a00\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;position&quot;:&quot;absolute&quot;,&quot;_transform_skewX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;_transform_skewY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-3.5,&quot;sizes&quot;:[]},&quot;_transform_skewX_effect_tablet_extra&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewX_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewX_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewY_effect_tablet_extra&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewY_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewY_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\">\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-571129d elementor-widget elementor-widget-an-forms-counter\" data-id=\"571129d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"an-forms-counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t\t<div class=\"progressWrapper\" aria-label=\"Petition Stimmen Fortschritt\" role=\"img\" id=\"progress-wrapper\">\n\t\t\t\t\t<div class=\"progress-circle\">\n\t\t\t\t\t\t<svg viewBox=\"0 0 160 160\">\n\t\t\t\t\t\t\t  <defs>\n\t\t\t\t\t\t\t\t  <linearGradient id=\"progress-gradient\" x1=\"0%\" y1=\"70%\" x2=\"100%\" y2=\"0%\">\n\t\t\t\t\t\t\t\t\t\t<stop class=\"stop-color-1\" offset=\"0%\" stop-color=\"#000000\"\/>\n\t\t\t\t\t\t\t\t\t\t<stop class=\"stop-color-2\" offset=\"100%\" stop-color=\"#ff0000\"\/>\n\t\t\t\t\t\t\t\t <\/linearGradient>\n\t\t\t\t\t\t\t<\/defs>\n\t\t\t\t\t\t\t<circle class=\"bg\" cx=\"80\" cy=\"80\" r=\"70\"><\/circle>\n\t\t\t\t\t\t\t<circle class=\"progress\" cx=\"80\" cy=\"80\" r=\"70\" stroke=\"url(#progress-gradient)\"><\/circle>\n\t\t\t\t\t\t\t<circle class=\"front\" cx=\"80\" cy=\"80\" r=\"61\"><\/circle>\n\t\t\t\t\t\t <\/svg>\n\t\t\t\t\t\t <div class=\"progress-text\" aria-live=\"polite\" aria-atomic=\"true\">\n\t\t\t\t\t\t\t <div class=\"number\" id=\"vote-count\"><\/div>\n\t\t\t\t\t\t\t<div class=\"label\" id=\"vote-label\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t  <\/div>\n\t\t\t\t\t <canvas id=\"confetti-canvas\"><\/canvas>\n\t\t\t\t<\/div>\n\t\t\t\t<script src=\"https:\/\/act.greens-efa.eu\/wp-content\/themes\/greensefa\/js\/confetti.browser.min.js\"><\/script>\n\t\t\t\t<script>\n\t\t\t\tjQuery(window).on(\"elementor\/frontend\/init\", () => {\n\t\t\t\t  elementorFrontend.hooks.addAction(\"frontend\/element_ready\/an-forms-counter.default\", ($scope) => {\n\t\t\t\t\t  const requiredVotes = 30000;\n\t\t\t\t\t  const currentVotes = 28416;\n\n\t\t\t\t\t  const progressCircle = document.querySelector(\".progress\");\n\t\t\t\t\t  const voteCount = document.getElementById(\"vote-count\");\n\t\t\t\t\t  const voteLabel = document.getElementById(\"vote-label\");\n\t\t\t\t\t  const progressWrapper = document.getElementById(\"progress-wrapper\");\n\t\t\t\t\t  const confettiCanvas = document.getElementById(\"confetti-canvas\");\n\n\t\t\t\t\t  if (!progressCircle || !voteCount || !voteLabel || !progressWrapper || !confettiCanvas) {\n\t\t\t\t\t\t  return;\n\t\t\t\t\t  }\n\n\t\t\t\t\t  const radius = 70;\n\t\t\t\t\t  const circumference = 2 * Math.PI * radius;\n\n\t\t\t\t\t  const progressPercent = Math.min(currentVotes \/ requiredVotes, 1);\n\t\t\t\t\t  const offset = circumference * (1 - progressPercent);\n\n\t\t\t\t\t  progressCircle.style.strokeDasharray = circumference;\n\t\t\t\t\t  progressCircle.style.strokeDashoffset = circumference;\n\n\t\t\t\t\t  voteCount.innerHTML = `<div class=\"currentVotes\">${currentVotes.toLocaleString()}<\/div><div class=\"requiredVotes\">\/ ${requiredVotes.toLocaleString()}<\/div>`;\n\t\t\t\t\t  voteLabel.innerHTML = \"<em>signatures<\/em>\";\n\n\t\t\t\t\t  const confettiInstance = confetti.create(confettiCanvas, { resize: true, useWorker: true });\n\n\t\t\t\t\t  function getProgressCenterInContainer() {\n\t\t\t\t\t\t const containerRect = progressWrapper.getBoundingClientRect();\n\t\t\t\t\t\t return {\n\t\t\t\t\t\t\tx: containerRect.width \/ 2,\n\t\t\t\t\t\t\ty: containerRect.height \/ 2\n\t\t\t\t\t\t };\n\t\t\t\t\t  }\n\n\t\t\t\t\t  const observer = new IntersectionObserver(\n\t\t\t\t\t\t entries => {\n\t\t\t\t\t\t\tentries.forEach(entry => {\n\t\t\t\t\t\t\t  if (entry.isIntersecting) {\n\t\t\t\t\t\t\t\t progressCircle.style.strokeDashoffset = offset;\n\n\t\t\t\t\t\t\t\t if (progressPercent === 1) {\n\t\t\t\t\t\t\t\t\tsetTimeout(() => {\n\t\t\t\t\t\t\t\t\t  launchSubtleFireworks();\n\t\t\t\t\t\t\t\t\t}, 1600);\n\t\t\t\t\t\t\t\t }\n\n\t\t\t\t\t\t\t\t observer.unobserve(entry.target);\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t});\n\t\t\t\t\t\t },\n\t\t\t\t\t\t { threshold: 0.5 }\n\t\t\t\t\t  );\n\t\t\t\t\t  setTimeout(() => {\n\t\t\t\t\t\t  observer.observe(progressCircle);\n\t\t\t\t\t  }, 1000);\n\n\t\t\t\t\t  function launchSubtleFireworks() {\n\t\t\t\t\t\t const containerRect = progressWrapper.getBoundingClientRect();\n\t\t\t\t\t\t const center = getProgressCenterInContainer();\n\t\t\t\t\t\t const duration = 2500;\n\t\t\t\t\t\t const animationEnd = Date.now() + duration;\n\n\t\t\t\t\t\t const defaults = {\n\t\t\t\t\t\t\tstartVelocity: 30,\n\t\t\t\t\t\t\tspread: 50,\n\t\t\t\t\t\t\tticks: 90,\n\t\t\t\t\t\t\tgravity: 1.6,\n\t\t\t\t\t\t\tdrift: 0.15,\n\t\t\t\t\t\t\tdecay: 0.9,\n\t\t\t\t\t\t\tscalar: 0.8,\n\t\t\t\t\t\t\tzIndex: 9999\n\t\t\t\t\t\t };\n\n\t\t\t\t\t\t (function frame() {\n\t\t\t\t\t\t\tconst timeLeft = animationEnd - Date.now();\n\t\t\t\t\t\t\tif (timeLeft <= 0) return;\n\n\t\t\t\t\t\t\tconst particleCount = 6 * (timeLeft \/ duration);\n\n\t\t\t\t\t\t\tfor (let i = 0; i < 3; i++) {\n\t\t\t\t\t\t\t  const angle = Math.random() * 2 * Math.PI;\n\t\t\t\t\t\t\t  const distance = 75 + (Math.random() * 15 - 7.5);\n\t\t\t\t\t\t\t  const x = center.x + distance * Math.cos(angle);\n\t\t\t\t\t\t\t  const y = center.y + distance * Math.sin(angle);\n\n\t\t\t\t\t\t\t  confettiInstance(Object.assign({}, defaults, {\n\t\t\t\t\t\t\t\t particleCount,\n\t\t\t\t\t\t\t\t origin: {\n\t\t\t\t\t\t\t\t\tx: x \/ containerRect.width,\n\t\t\t\t\t\t\t\t\ty: y \/ containerRect.height\n\t\t\t\t\t\t\t\t },\n\t\t\t\t\t\t\t\t colors: [\"#a3e635\", \"#bef264\", \"#4ade80\", \"#22c55e\", \"#16a34a\"]\n\t\t\t\t\t\t\t  }));\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\trequestAnimationFrame(frame);\n\t\t\t\t\t\t })();\n\t\t\t\t\t  }\n\t\t\t\t  });\n\t\t\t\t});\n\t\t\t\t<\/script>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f073afd elementor-widget elementor-widget-heading\" data-id=\"1f073afd\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"take-action\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Soutenez notre appel en faveur d'une taxe europ\u00e9enne sur les tech bros.<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-270d676 elementor-widget elementor-widget-heading\" data-id=\"270d676\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Signez notre p\u00e9tition ici \ud83d\udc47<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21253784 elementor-widget elementor-widget-an-forms\" data-id=\"21253784\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"an-forms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"form466701197\"><script src='https:\/\/actionnetwork.org\/widgets\/v6\/form\/digital-services-tax-3?format=js&source=website&style=full'><\/script><div id='can-form-area-digital-services-tax-3' style='width: 100%'><!-- this div is the target for our HTML insertion --><\/div><\/div><script>\n\t\t\t(function ( $ ) {\n\t\t\t\t$(document).on(\"can_embed_loaded\", function(e) {\n\t\t\t\t\tsetTimeout( function(){\n\t\t\t\t\t\tvar $form466701197 = $(\"#form466701197\");\n\t\t\t\t\t\tvar $redirect = \"\";\n\n\t\t\t\t\t\tif ( $redirect !== \"\" ) {\n\t\t\t\t\t\t\t$form466701197.find(\"#redirect\").remove();\n\t\t\t\t\t\t\t$form466701197.find(\"form\").prepend(\n\t\t\t\t\t\t\t\t'<input id=\"redirect\" name=\"redirect\" type=\"hidden\" value=\"' + $redirect + '\" \/>'\n\t\t\t\t\t\t\t);\n\t\t\t\t\t\t}\n\t\t\t\t\t}, 100);\n\t\t\t\t});\n\t\t\t})( jQuery );\n\t\t<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d0fb54d e-con-full e-flex e-con e-child\" data-id=\"d0fb54d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Taxer les tech bros : make them pay Take action Les citoyen\u00b7nes europ\u00e9en\u00b7nes travaillent dur pour gagner leur vie et subvenir aux besoins de leur famille. Pendant ce temps, les dirigeants ultra-riches des g\u00e9ants de la tech engrangent des b\u00e9n\u00e9fices records sans contribuer \u00e0 la soci\u00e9t\u00e9. Et tout cela avec le soutien du pr\u00e9sident am\u00e9ricain [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"class_list":["post-4545","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/act.greens-efa.eu\/fr\/wp-json\/wp\/v2\/pages\/4545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/act.greens-efa.eu\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/act.greens-efa.eu\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/act.greens-efa.eu\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/act.greens-efa.eu\/fr\/wp-json\/wp\/v2\/comments?post=4545"}],"version-history":[{"count":16,"href":"https:\/\/act.greens-efa.eu\/fr\/wp-json\/wp\/v2\/pages\/4545\/revisions"}],"predecessor-version":[{"id":7141,"href":"https:\/\/act.greens-efa.eu\/fr\/wp-json\/wp\/v2\/pages\/4545\/revisions\/7141"}],"wp:attachment":[{"href":"https:\/\/act.greens-efa.eu\/fr\/wp-json\/wp\/v2\/media?parent=4545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}